{"id":430,"date":"2021-05-11T11:40:33","date_gmt":"2021-05-11T15:40:33","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=430"},"modified":"2021-05-15T21:07:11","modified_gmt":"2021-05-16T01:07:11","slug":"opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/","title":{"rendered":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia"},"content":{"rendered":"\r\n<blockquote>\r\n<h4><strong>En el D\u00eda Internacional de la Verificaci\u00f3n de Datos, el portal venezolano EsPaja.com revela c\u00f3mo la emergencia sanitaria por COVID-19 ha servido de excusa para la manipulaci\u00f3n y la propagaci\u00f3n de noticias falsas<\/strong><\/h4>\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong><em>Transparencia Venezuela, 2 de abril de 2021<\/em><\/strong>. Por iniciativa de la Red Internacional de Verificadores de Datos, organizaci\u00f3n liderada por el Instituto Poynter, cada 2 de abril se celebra el <strong>D\u00eda Internacional de la Verificaci\u00f3n de Datos<\/strong> (International Fact-Checking Day). La fecha ocurre un d\u00eda despu\u00e9s del primero de abril, cuando en varios pa\u00edses se conmemora el equivalente al D\u00eda de los Santos Inocentes (April Fools\u2019 Day), donde los medios de comunicaci\u00f3n se suelen prestar para publicar noticias falsas y sat\u00edricas.\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El prop\u00f3sito del Fact Checking Day es promover una cultura de apego por la verdad, tanto a nivel pol\u00edtico, period\u00edstico, como en la ciudadan\u00eda en general. Esta iniciativa cobra especial importancia en el contexto de la <strong>pandemia global por COVID-19<\/strong>, evento que, seg\u00fan lo han se\u00f1alado organismos internacionales como Naciones Unidas y Human Rights Watch, ha servido de excusa para justificar restricciones a derechos ciudadanos como el libre tr\u00e1nsito y el acceso a la informaci\u00f3n p\u00fablica. De igual modo, a poco m\u00e1s de un a\u00f1o de iniciada la crisis, se han multiplicado en diversos pa\u00edses la opacidad, la desinformaci\u00f3n y la propagaci\u00f3n de noticias potencialmente falsas asociadas con el virus y el manejo de la emergencia.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En Venezuela, <strong>las desinformaciones tienen el sello del Estado<\/strong>. La llegada de la pandemia no solo ha exacerbado la Emergencia Humanitaria Compleja preexistente en el pa\u00eds producto de la corrupci\u00f3n, sino que ha intensificado tambi\u00e9n los patrones de opacidad, desinformaci\u00f3n, manipulaci\u00f3n y persecuci\u00f3n que se han registrado en las dos \u00faltimas d\u00e9cadas, seg\u00fan lo denunciado por diversas organizaciones de la sociedad civil.\u00a0 Para ayudar a comprender esta realidad y dotar a los ciudadanos de herramientas para hacer frente a la desinformaci\u00f3n, <strong>Transparencia Venezuela<\/strong> cre\u00f3 en octubre de 2019 el portal de verificaci\u00f3n de datos <strong>EsPaja.com<\/strong>.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Del seguimiento realizado por el equipo de la p\u00e1gina se desprende que los <strong>espacios informativos independientes escasean<\/strong> debido a la hegemon\u00eda comunicacional del oficialismo y los ataques a la prensa libre, adem\u00e1s debido a la opacidad en datos oficiales. El Colegio Nacional de Periodistas (CNP) estima que desde 1999 se han cerrado m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds.\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Asimismo, de acuerdo con el m\u00e1s reciente reporte anual del Instituto Prensa y Sociedad de Venezuela (IPYS), al cierre de 2020 hubo 374 casos que acumularon <strong>636 violaciones a las garant\u00edas de libre expresi\u00f3n e informaci\u00f3n<\/strong> en entornos tradicionales y digitales. En consecuencia, los mensajes de la administraci\u00f3n de Nicol\u00e1s Maduro tienen una mayor exposici\u00f3n en los medios tradicionales, al igual que en las plataformas digitales.\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center;\"><strong>Lee m\u00e1s\u00a0<\/strong><\/p>\r\n<p style=\"text-align: center;\"><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/14\/la-informacion-sobre-la-compra-de-vacunas-no-debe-ser-secreto-de-estado\/\"><strong>La informaci\u00f3n sobre la compra de vacunas no debe ser secreto de Estado<\/strong><\/a><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>El Observatorio de Entorno Digital ProBox public\u00f3 en su informe anual que el oficialismo domin\u00f3 la conversaci\u00f3n en Twitter, con 37% del total de tendencias registradas en 2020. El conglomerado de cuentas alineadas al chavismo gener\u00f3 el 84% de los tuits que se publicaron en el a\u00f1o y, en promedio, m\u00e1s de 60% de los mensajes fueron hechos por posibles bots o cuentas falsas.\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pero en vez de utilizar este alcance para difundir informaci\u00f3n veraz, el gobierno venezolano recurre de forma sistem\u00e1tica a la <strong>manipulaci\u00f3n y a la desinformaci\u00f3n.<\/strong> A finales de marzo de este a\u00f1o, Facebook suspendi\u00f3 la p\u00e1gina de Nicol\u00e1s Maduro por violar sus pol\u00edticas al compartir informaci\u00f3n err\u00f3nea sobre presuntos tratamientos contra COVID-19.\u00a0 La medida se aplic\u00f3 en directa alusi\u00f3n a un video que public\u00f3 el mandatario el pasado mes de enero, en el que asegur\u00f3 que las gotas de Carvativir, tambi\u00e9n conocido como \u00abgotas milagrosas de Jos\u00e9 Gregorio Hern\u00e1ndez\u201d, son eficaces contra la enfermedad.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El Ministerio de Comunicaci\u00f3n e Informaci\u00f3n calific\u00f3 la decisi\u00f3n de Facebook como arbitraria, pero Twitter hizo lo mismo en marzo del a\u00f1o pasado cuando elimin\u00f3 publicaciones en las que el mandatario divulg\u00f3 tres documentos sobre supuestas investigaciones desarrolladas por Sirio Quintero, a quien calific\u00f3 como \u00abdoctor\u00bb.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Entre los tratamientos divulgados por las autoridades venezolanas, tambi\u00e9n se cuentan f\u00e1rmacos como cloroquina y ivermectina en los esquemas de tratamiento del Ministerio de Salud, a pesar de que la Organizaci\u00f3n Panamericana de la Salud (OPS) ha desaconsejado el uso de todos ellos.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center;\"><strong>Lee m\u00e1s\u00a0<\/strong><\/p>\r\n<p style=\"text-align: center;\"><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/15\/gobierno-prioriza-ingreso-de-vacunas-contra-la-covid-19-de-rusia-y-china\/\"><strong>Gobierno prioriza ingreso de vacunas contra la COVID-19 de Rusia y China<\/strong><\/a><\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Actualmente, el foco de la desinformaci\u00f3n gubernamental en materia cient\u00edfica est\u00e1 sobre el tema de las vacunas. La OPS reserv\u00f3 para Venezuela, mediante el mecanismo Covax, 12 millones de dosis fabricadas por AstraZeneca. No obstante, las autoridades nacionales la prohibieron, argumentando \u00absoberan\u00eda cient\u00edfica\u00bb y mostrando dudas a partir de la m\u00ednima cantidad de casos de trombosis que se han reportado a nivel mundial, en los cuales no se ha determinado una relaci\u00f3n directa con ese f\u00e1rmaco. Por ello, la Organizaci\u00f3n Mundial de la Salud (OMS) ha recomendado continuar su aplicaci\u00f3n.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Seg\u00fan registros de <strong>EsPaja.com<\/strong>, al cierre del primer a\u00f1o de pandemia en el pa\u00eds, hasta el 13 de marzo de 2021, 57% de las verificaciones realizadas a voceros del gobierno resultaron falsas. En cambio, el 29% fue calificado como cierto o dentro del espectro de la verdad, mientras que 14% result\u00f3 discutible.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En el marco del D\u00eda Internacional de la Verificaci\u00f3n de Datos, <strong>EsPaja.com<\/strong> impulsa la formaci\u00f3n period\u00edstica y ciudadana para evitar caer en noticias falsas. Por una parte, a trav\u00e9s del m\u00e9todo Detente, Duda, Busca y Coopera que se puede descargar en la gu\u00eda preparada junto a <strong>Transparencia Venezuela<\/strong> y la organizaci\u00f3n Espacio P\u00fablico. Por la otra, mediante los cursos de formaci\u00f3n en la materia organizan en conjunto con el portal de capacitaci\u00f3n en l\u00ednea <strong>Campus Transparencia<\/strong>.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Para conocer el listado de 10 herramientas (la mayor\u00eda de ellas gratuitas) recomendadas por <strong>EsPaja.com<\/strong> que todo periodista digital deber\u00eda tener a la mano para utilizar adecuadamente la informaci\u00f3n que encuentran en redes sociales, ingresa a <a href=\"https:\/\/bit.ly\/3rGbaed\">https:\/\/bit.ly\/3rGbaed<\/a>\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con el m\u00e1s reciente reporte anual del Instituto Prensa y Sociedad de Venezuela (IPYS), al cierre de 2020 hubo 374 casos que acumularon 636 violaciones a las garant\u00edas de libre expresi\u00f3n e informaci\u00f3n en entornos tradicionales y digitales. <\/p>\n","protected":false},"author":1,"featured_media":1792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desinformacion-y-vacunacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T15:40:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-16T01:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia\",\"datePublished\":\"2021-05-11T15:40:33+00:00\",\"dateModified\":\"2021-05-16T01:07:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\"},\"wordCount\":1104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg\",\"articleSection\":[\"Desinformaci\u00f3n y vacunaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\",\"name\":\"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg\",\"datePublished\":\"2021-05-11T15:40:33+00:00\",\"dateModified\":\"2021-05-16T01:07:11+00:00\",\"description\":\"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica","description":"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/","og_locale":"es_ES","og_type":"article","og_title":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica","og_description":"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-05-11T15:40:33+00:00","article_modified_time":"2021-05-16T01:07:11+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia","datePublished":"2021-05-11T15:40:33+00:00","dateModified":"2021-05-16T01:07:11+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/"},"wordCount":1104,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg","articleSection":["Desinformaci\u00f3n y vacunaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/","name":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg","datePublished":"2021-05-11T15:40:33+00:00","dateModified":"2021-05-16T01:07:11+00:00","description":"El Colegio Nacional de Periodistas estima que desde 1999 m\u00e1s de 600 medios de comunicaci\u00f3n en el pa\u00eds han cerrado. Investigamos al respecto","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/Opacidad-y-desinformacion-impera-sobre-vacunaciones-de-covid-19-en-venezuela-video-300x169-1.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/11\/opacidad-y-desinformacion-marcan-la-agenda-publica-en-tiempos-de-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Opacidad y desinformaci\u00f3n marcan la agenda p\u00fablica en tiempos de pandemia"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":8,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/430\/revisions"}],"predecessor-version":[{"id":1822,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/430\/revisions\/1822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/1792"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}