{"id":3914,"date":"2021-11-15T18:53:03","date_gmt":"2021-11-15T22:53:03","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3914"},"modified":"2021-11-15T18:55:16","modified_gmt":"2021-11-15T22:55:16","slug":"2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/","title":{"rendered":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>Transparencia Venezuela, 15 de noviembre de 2021.-<\/strong> Este 13 de noviembre, Venezuela <strong>recibi\u00f3 2.587.200 dosis de Sinopharm adquiridas a trav\u00e9s de Covax<\/strong>, el mecanismo global de acceso a vacunas anti-COVID-19.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">De acuerdo con la Organizaci\u00f3n Panamericana de la Salud (OPS), la entrega se registr\u00f3 en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar en presencia del <strong>Ministerio de Salud<\/strong> y de representantes del organismo internacional.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cLa OPS\/OMS ha acompa\u00f1ado a las autoridades nacionales de salud en la implementaci\u00f3n de los pilares de la respuesta a la pandemia de COVID-19, incluyendo:<strong> vigilancia epidemiol\u00f3gica e investigaci\u00f3n de casos<\/strong>, dotaci\u00f3n de insumos de laboratorio para el diagn\u00f3stico de COVID-19, intervenciones de prevenci\u00f3n y control de infecciones en establecimientos de salud,<strong> capacitaci\u00f3n a personal asistencial en manejo cl\u00ednico de los casos<\/strong>, apoyo log\u00edstico para la dotaci\u00f3n de insumos a los servicios de salud de todo el pa\u00eds\u201d, rese\u00f1a la OPS en su p\u00e1gina web.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/09\/conoce-el-camino-transitado-por-venezuela-para-adquirir-las-vacunas-a-traves-de-covax\/\">Leer m\u00e1s: Conoce el camino transitado por Venezuela para adquirir las vacunas a trav\u00e9s de Covax<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Este es el tercer cargamento que env\u00eda Covax a Venezuela. El primero lleg\u00f3 el 6 de septiembre con <strong><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/07\/venezuela-recibe-693-600-dosis-de-sinovac-a-traves-de-covax\/\">693.600 dosis de Sinovac<\/a><\/strong> y el segundo arrib\u00f3 el 9 de octubre con 2.594.400 dosis de Sinopharm. Sumando el cargamento del 13 de noviembre, <strong>han llegado hasta ahora 5.875.200 dosis<\/strong>. Esta cantidad representa 48,6% de la compra hecha a Covax por un total de 12.068.000 vacunas que servir\u00e1n para inmunizar a 20% de la poblaci\u00f3n.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/10\/11\/venezuela-recibe-2-594-400-dosis-de-sinopharm-a-traves-de-covax\/\">Leer m\u00e1s:<\/a> <a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/10\/11\/venezuela-recibe-2-594-400-dosis-de-sinopharm-a-traves-de-covax\/\">Venezuela recibe 2.594.400 dosis de Sinopharm a trav\u00e9s de Covax<\/a><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Hoy recibimos el 3\u00b0 env\u00edo de 2.5 millones de vacunas contra la COVID-19 a trav\u00e9s del mecanismo COVAX, para continuar avanzando en la vacunaci\u00f3n masiva del pueblo. Gracias a los esfuerzos que realiza el Pdte. <a href=\"https:\/\/twitter.com\/NicolasMaduro?ref_src=twsrc%5Etfw\">@NicolasMaduro<\/a> continuamos protegiendo la Salud y Vida de todas y todos. <a href=\"https:\/\/t.co\/jbRBOBbRyR\">pic.twitter.com\/jbRBOBbRyR<\/a><\/p>\n<p>&mdash; Carlos Alvarado (@AlvaradoC_Salud) <a href=\"https:\/\/twitter.com\/AlvaradoC_Salud\/status\/1459596408957321216?ref_src=twsrc%5Etfw\">November 13, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3918\" src=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/covax-Venezuela.jpg\" alt=\"\" width=\"1110\" height=\"614\" srcset=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/covax-Venezuela.jpg 1110w, https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/covax-Venezuela-300x166.jpg 300w, https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/covax-Venezuela-1024x566.jpg 1024w\" sizes=\"(max-width: 1110px) 100vw, 1110px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega <\/p>\n","protected":false},"author":1,"featured_media":3915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[77,90,74,71,73],"class_list":["post-3914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-covid-19","tag-ministerio-de-salud","tag-ops","tag-vacunas","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T22:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T22:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1420\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax\",\"datePublished\":\"2021-11-15T22:53:03+00:00\",\"dateModified\":\"2021-11-15T22:55:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png\",\"keywords\":[\"COVID-19\",\"Ministerio de Salud\",\"OPS\",\"vacunas\",\"Venezuela\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\",\"name\":\"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png\",\"datePublished\":\"2021-11-15T22:53:03+00:00\",\"dateModified\":\"2021-11-15T22:55:16+00:00\",\"description\":\"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png\",\"width\":1420,\"height\":710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica","description":"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/","og_locale":"es_ES","og_type":"article","og_title":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica","og_description":"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-11-15T22:53:03+00:00","article_modified_time":"2021-11-15T22:55:16+00:00","og_image":[{"width":1420,"height":710,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png","type":"image\/png"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax","datePublished":"2021-11-15T22:53:03+00:00","dateModified":"2021-11-15T22:55:16+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png","keywords":["COVID-19","Ministerio de Salud","OPS","vacunas","Venezuela"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/","name":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png","datePublished":"2021-11-15T22:53:03+00:00","dateModified":"2021-11-15T22:55:16+00:00","description":"Con este tercer cargamento, Venezuela suma 5.875.200 dosis de vacunas anti-COVID-19 provenientes del mecanismo Covax. Faltar\u00edan casi 6 millones de dosis para completar la entrega","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/11\/tercer_envio_covax_ven.png","width":1420,"height":710},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/11\/15\/2-587-200-dosis-de-sinopharm-llegaron-a-venezuela-por-medio-de-covax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"2.587.200 dosis de Sinopharm llegaron a Venezuela por medio de Covax"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3914"}],"version-history":[{"count":4,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3914\/revisions"}],"predecessor-version":[{"id":3920,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3914\/revisions\/3920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/3915"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}