{"id":3384,"date":"2021-09-05T14:40:29","date_gmt":"2021-09-05T18:40:29","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3384"},"modified":"2021-09-08T14:42:45","modified_gmt":"2021-09-08T18:42:45","slug":"conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/","title":{"rendered":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 5 de septiembre de 2021.- <\/strong>Ante la inexistencia de estad\u00edsticas oficiales que permitan a los venezolanos conocer c\u00f3mo avanza la vacunaci\u00f3n contra el coronavirus en el pa\u00eds, <strong>sectores cient\u00edficos y acad\u00e9micos del pa\u00eds se han dado a la tarea de consultar a la ciudadan\u00eda<\/strong>, v\u00eda telef\u00f3nica o presencial, algunos datos sobre su experiencia en la vacunaci\u00f3n con el fin de hacer proyecciones y acercarse a la cantidad de personas que cuentan con una dosis de vacuna y que han culminado su esquema de vacunaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>A continuaci\u00f3n te mostramos los resultados de dos estudios realizados en el mes de agosto. El primero fue presentado por el infect\u00f3logo<strong> Julio Castro<\/strong> el 2 de septiembre, mientras que el segundo fue publicado por la <strong>Encuestadora Delphos y la Unidad de Pol\u00edticas P\u00fablicas de la Universidad Sim\u00f3n Bol\u00edvar<\/strong> el 5 de septiembre.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>En Venezuela podr\u00eda haber 3,3 millones de personas con el esquema de vacunaci\u00f3n completo\u00a0<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>A trav\u00e9s de un estudio de opini\u00f3n que se realiz\u00f3 en todo el pa\u00eds a mayores de 18 a\u00f1os, una comunidad cient\u00edfica representada por el infect\u00f3logo Julio Castro proyect\u00f3 que<strong> 3.376.080 personas<\/strong> (11,7% de la poblaci\u00f3n)\u00a0 en Venezuela han recibido las dos dosis de vacunas contra el coronavirus y 6.442.900 personas cuentan con una sola dosis. Quiere decir que se han aplicado <strong>9.818.980 dosis<\/strong>. Para llegar a este resultado, se aplicaron 2.436 encuestas v\u00eda telef\u00f3nica en 290 municipios desde el 23 hasta el 27 agosto.<\/p>\n<p>&nbsp;<\/p>\n<p>Sobre la marca de vacuna se obtuvo que 78,9% (8.057.205) de la dosis aplicadas son de <strong>Sinopharm<\/strong> y 21% (1.739.293) de <strong>Sputnik-V.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Respecto al porcentaje de Sinopharm, 41,5% cuenta con una dosis y 58,5% con las dos. Mientras que sobre la Sputnik-V, 71,5% tiene la primera dosis y <strong>28,5% culmin\u00f3 el esquema<\/strong>. Castro destac\u00f3 que a partir de estos datos, se estima que <strong>900.000 personas faltan por recibir su segunda dosis<\/strong> de vacuna rusa, usada en Venezuela para los mayores de 60 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>El proceso de vacunaci\u00f3n en el pa\u00eds inici\u00f3 en febrero. Sin embargo, <strong>71% de los encuestados report\u00f3 haber recibido su \u00faltima dosis de vacuna entre julio y agosto<\/strong>, en el que se registr\u00f3 4,1% de crecimiento intermensual.<\/p>\n<p>&nbsp;<\/p>\n<p>El m\u00e9dico infect\u00f3logo se\u00f1ala que al menos 450.000 personas han recibido el mensaje de convocatoria para vacunarse, pero no pudieron ser atendidos. <span style=\"font-weight: 400;\">M\u00e1s de 28% de los consultados respondi\u00f3 que no hab\u00eda vacunas en el centro al momento de aplicarse la segunda dosis.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Solo <strong>12,60% de los encuestados entre 65 a\u00f1os o m\u00e1s han completado su esquema de vacunaci\u00f3n.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/07\/venezuela-recibe-693-600-dosis-de-sinovac-a-traves-de-covax\/\">Leer m\u00e1s:<\/a>\u00a0<a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/07\/venezuela-recibe-693-600-dosis-de-sinovac-a-traves-de-covax\/\">Venezuela recibe 693.600 dosis de Sinovac a trav\u00e9s de Covax\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>79,3% de la poblaci\u00f3n no ha recibido ni una dosis de vacuna anti-COVID-19<\/h3>\n<p>&nbsp;<\/p>\n<p>La encuestadora Delphos y la Unidad de Pol\u00edticas P\u00fablicas de la Universidad Sim\u00f3n Bol\u00edvar (USB) publicaron la segunda parte de una investigaci\u00f3n que revela que al menos<strong> 8,1% de la poblaci\u00f3n venezolana<\/strong> est\u00e1 totalmente vacunada contra el coronavirus hasta el 28 de agosto de 2021. Mientras que la cobertura con una dosis llega a 12,6% de la poblaci\u00f3n. Es decir, 79,3% de los que habitan Venezuela no han recibido ni una sola dosis de vacuna.<\/p>\n<p>&nbsp;<\/p>\n<p>Si se toma como referencia la poblaci\u00f3n de Venezuela seg\u00fan la Organizaci\u00f3n Panamericana de la Salud, que es de 28.704.947 habitantes, el porcentaje revelado quiere decir que m\u00e1s de <strong>2,3<\/strong><strong> millones de personas han culminado su esquema de vacunaci\u00f3n con Sinopharm y Sputnik-V<\/strong>, que son las aprobadas en el pa\u00eds por el Ministerio de Salud.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta cobertura deja a Venezuela en el lugar<strong> n\u00b0 17 de 20 pa\u00edses de Am\u00e9rica Latina<\/strong>. . Para esa fecha, los pa\u00edses con mayor cobertura completa<br \/>\nen la regi\u00f3n eran Uruguay (71,6%), y Chile (70,1%).<\/p>\n<p>&nbsp;<\/p>\n<p>Para este estudio fueron entrevistadas<strong> 1.200 personas entre el 18 y 28 de agosto<\/strong>, en poblaciones con 1.000 habitantes o m\u00e1s. Los investigadores concluyeron que la mayor cobertura de inmunizaci\u00f3n se ha dado en la poblaci\u00f3n\u00a0<strong>mayor a 50 a\u00f1os con 16%.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>De acuerdo con datos de la OPS al 27 de agosto de 2021, <strong>6.006.270 ciudadanos han recibido la primera dosis y 3.336.547 cuentan con las dosis de vacuna<\/strong>. Seg\u00fan estos datos que proporciona el pa\u00eds a la OPS, 21% de la poblaci\u00f3n est\u00e1 parcialmente vacunada y 11,6% complet\u00f3 el esquema de vacunaci\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V<\/p>\n","protected":false},"author":1,"featured_media":3395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[191,77,136,152,83],"class_list":["post-3384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-academia","tag-covid-19","tag-sinopharm","tag-sputnik-v","tag-vacunacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-05T18:40:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-08T18:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos\",\"datePublished\":\"2021-09-05T18:40:29+00:00\",\"dateModified\":\"2021-09-08T18:42:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\"},\"wordCount\":782,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg\",\"keywords\":[\"Academia\",\"COVID-19\",\"Sinopharm\",\"Sputnik-V\",\"vacunaci\u00f3n\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\",\"name\":\"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg\",\"datePublished\":\"2021-09-05T18:40:29+00:00\",\"dateModified\":\"2021-09-08T18:42:45+00:00\",\"description\":\"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica","description":"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica","og_description":"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-09-05T18:40:29+00:00","article_modified_time":"2021-09-08T18:42:45+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos","datePublished":"2021-09-05T18:40:29+00:00","dateModified":"2021-09-08T18:42:45+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/"},"wordCount":782,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg","keywords":["Academia","COVID-19","Sinopharm","Sputnik-V","vacunaci\u00f3n"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/","name":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg","datePublished":"2021-09-05T18:40:29+00:00","dateModified":"2021-09-08T18:42:45+00:00","description":"Entre 8% y 11% proyectan dos estudios de opini\u00f3n la cobertura completa de vacunaci\u00f3n contra el coronavirus. La mayor cantidad de dosis aplicadas se corresponden a Sinopharm y se estima que 900.000 personas a\u00fan faltan por segunda dosis de Sputnik-V","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/09\/vacunacion-9.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/09\/05\/conoce-las-proyecciones-de-vacunacion-anti-covid-19-de-sectores-cientificos-venezolanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Conoce las proyecciones de vacunaci\u00f3n anti-COVID-19 de sectores cient\u00edficos venezolanos"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3384"}],"version-history":[{"count":3,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3384\/revisions"}],"predecessor-version":[{"id":3397,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3384\/revisions\/3397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/3395"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}