{"id":3152,"date":"2021-08-18T16:31:02","date_gmt":"2021-08-18T20:31:02","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3152"},"modified":"2021-08-18T16:31:02","modified_gmt":"2021-08-18T20:31:02","slug":"ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/","title":{"rendered":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela. Sin embargo, en la p\u00e1gina web del organismo se indica que casi 118.000 personas han culminado su esquema contra el coronavirus\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 18 de agosto de 2021.-<\/strong> <span style=\"font-weight: 400;\">Ser m\u00e1s estrictos con el distanciamiento f\u00edsico y el uso de mascarillas son las recomendaciones que hace la Organizaci\u00f3n Panamericana de la Salud (OPS) ante la falta de <strong>segundas dosis de vacunas<\/strong> contra el coronavirus que reporta Venezuela desde el mes de junio.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Este 18 de agosto, el director de Emergencias en Salud de la OPS, Ciro Ugarte, record\u00f3 que todas las autoridades del organismo han insistido en que el uso de tapabocas, el distanciamiento y <strong>la desinfecci\u00f3n de manos han sido altamente efectivos<\/strong> para reducir la transmisi\u00f3n del virus.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cEviten aglomeraciones, y si aparece alg\u00fan s\u00edntoma, deben aislarse y tomar cuarentena\u201d, asegur\u00f3 Ugarte en rueda de prensa al ser consultado sobre qu\u00e9 hacer en Venezuela ante la falta de segundas dosis, espec\u00edficamente de Sputnik-V.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Hasta este 18 de agosto de 2021, el gobierno de Nicol\u00e1s Maduro <strong>no ha presentado un cronograma sobre la vacunaci\u00f3n con este segundo componente ni ha explicado a los venezolanos<\/strong> por qu\u00e9 desde el 12 de junio no ha llegado un nuevo cargamento con\u00a0 vacunas. El 17 de agosto, en rueda de prensa, el mandatario se\u00f1al\u00f3 que ser\u00eda la Comisi\u00f3n Presidencial para el Control y la Prevenci\u00f3n de la COVID-19 la encargada de definir cu\u00e1ndo se aplicar\u00edan las segundas dosis.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/17\/en-seis-meses-venezuela-ha-vacunado-completamente-a-04-de-su-poblacion-segun-ops\/\">Leer m\u00e1s:<\/a>\u00a0<a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/17\/en-seis-meses-venezuela-ha-vacunado-completamente-a-04-de-su-poblacion-segun-ops\/\">En seis meses Venezuela ha vacunado completamente a 0,4% de su poblaci\u00f3n, seg\u00fan OPS<\/a><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El 4 de agosto, el equipo de Sputnik-V public\u00f3 un comunicado en el que indica que <\/span><a href=\"https:\/\/mundo.sputniknews.com\/20210804\/rusia-resolvera-demoras-en-exportaciones-del-segundo-componente-de-sputnik-v-en-agosto-1114780967.html\"><b>en este mes \u00abse resolver\u00e1n por completo todos los retrasos temporales<\/b><\/a><span style=\"font-weight: 400;\"> en la entrega del segundo componente de la vacuna\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por otra parte, Ugarte se\u00f1al\u00f3 que <strong>no cuentan con informaci\u00f3n detallada<\/strong> y actualizada sobre la vacunaci\u00f3n en Venezuela. \u201cSabemos que la informaci\u00f3n se comparte en las reuniones internas que tiene la representaci\u00f3n de la OPS en Venezuela con el gobierno. Estamos haciendo seguimiento para la llegada de vacunas adicionales\u201d, expres\u00f3.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, en una actualizaci\u00f3n del 17 de agosto de 2021, la OPS reporta en su p\u00e1gina web que <strong>al menos 117.000 personas<\/strong> han culminado el esquema de vacunaci\u00f3n contra el COVID-19. Mientras que <\/span><span style=\"font-weight: 400;\">3.612.473 han recibido solo la primera dosis de vacuna.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ambos datos difieren de la informaci\u00f3n ofrecida por el ministro de Salud, Carlos Alvarado, el 1\u00b0 de agosto:<strong> 4.677.000 personas han recibido al menos una dosis de vacuna<\/strong>. Esto a su vez, tampoco coincide con la cantidad de dosis que han llegado, seg\u00fan anuncios p\u00fablicos: 3.230.000 dosis, entre Sinopharm y Sputnik-V.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/carabobo-vacunacion-organizada-por-fedecamaras-alcanzo-a-al-menos-1-500-trabajadores-del-sector-privado\/\">Leer m\u00e1s:\u00a0<\/a><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/carabobo-vacunacion-organizada-por-fedecamaras-alcanzo-a-al-menos-1-500-trabajadores-del-sector-privado\/\">Carabobo | Vacunaci\u00f3n organizada por Fedec\u00e1maras alcanz\u00f3 a al menos 1.500 trabajadores del sector privado<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela<\/p>\n","protected":false},"author":1,"featured_media":3153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[77,170,169,74,152],"class_list":["post-3152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-covid-19","tag-cronograma","tag-distanciamiento-fisico","tag-ops","tag-sputnik-v"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-18T20:31:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela\",\"datePublished\":\"2021-08-18T20:31:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg\",\"keywords\":[\"COVID-19\",\"cronograma\",\"Distanciamiento f\u00edsico\",\"OPS\",\"Sputnik-V\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\",\"name\":\"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg\",\"datePublished\":\"2021-08-18T20:31:02+00:00\",\"description\":\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica","description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica","og_description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-08-18T20:31:02+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela","datePublished":"2021-08-18T20:31:02+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg","keywords":["COVID-19","cronograma","Distanciamiento f\u00edsico","OPS","Sputnik-V"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/","name":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg","datePublished":"2021-08-18T20:31:02+00:00","description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, asegur\u00f3 que no manejan cifras actualizadas de la vacunaci\u00f3n en Venezuela","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/personas-con-tapabocas.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/18\/ops-recomienda-acentuar-medidas-de-bioseguridad-ante-escasez-de-segundas-dosis-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"OPS recomienda acentuar medidas de bioseguridad ante escasez de segundas dosis en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":2,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"predecessor-version":[{"id":3155,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3152\/revisions\/3155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/3153"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}