{"id":3094,"date":"2021-08-11T15:58:33","date_gmt":"2021-08-11T19:58:33","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3094"},"modified":"2021-08-11T15:58:33","modified_gmt":"2021-08-11T19:58:33","slug":"ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/","title":{"rendered":"OPS: \u00abPrimer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que las primeras vacunas que llegar\u00e1n por Covax ser\u00e1n Sinovac. Se\u00f1al\u00f3 que a\u00fan est\u00e1n en curso los tr\u00e1mites administrativos entre la OPS, Covax y Venezuela\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 11 de agosto de 2021.-\u00a0<\/strong>El primer cargamento de vacunas anti-COVID-19 compradas a Covax <strong>podr\u00eda arribar a finales del mes de agosto<\/strong>, asegur\u00f3 este mi\u00e9rcoles la Organizaci\u00f3n Panamericana de la Salud. El director de Emergencias en Salud de este organismo, Ciro Ugarte, precis\u00f3 que en ese env\u00edo llegar\u00e1n <strong>dosis de Sinovac.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ugarte se\u00f1al\u00f3 que la log\u00edstica depender\u00e1 de los tr\u00e1mites administrativos que est\u00e1n completando Covax, Venezuela y la OPS. \u00abEn este primer cargamento corresponder\u00eda Sinovac, seguidas de Sinopharm hasta completar las vacunas comprometidas en esta ronda de distribuci\u00f3n\u00bb, dijo.<\/p>\n<p>&nbsp;<\/p>\n<p>El pasado 4 de agosto, la OPS inform\u00f3 que entre agosto y septiembre el mecanismo Covax <strong><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\">enviar\u00eda 3.288.000 dosis<\/a><\/strong>, de las cuales poco m\u00e1s de 2,5 millones son de Sinopharm y 600.000 de Sinovac.<\/p>\n<p>&nbsp;<\/p>\n<p>Las autoridades de Venezuela se han propuesto vacunar a 70% de la poblaci\u00f3n al cierre de 2021. Esto significar\u00eda inmunizar a al menos 22 millones de personas y para cumplir con la meta se necesitar\u00edan 44 millones de dosis. Sin embargo, de forma p\u00fablica al pa\u00eds<strong> han llegado 3.230.000 vacunas<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Nueva oportunidad para acceder a vacunas anti-COVID-19<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>En esta \u00faltima semana, la OPS recibi\u00f3 reportes<strong> de 1,3 millones de casos de COVID-19 y 19.000 muertes en la regi\u00f3n<\/strong>. La cobertura de vacunas sigue siendo baja, dijo la directora de la organizaci\u00f3n, Carissa Etienne. En ese sentido, anunci\u00f3 este 11 de agosto que la OPS est\u00e1 recibiendo solicitudes de pa\u00edses interesados en <strong>adquirir m\u00e1s vacunas que complementen las que han comprado a Covax o a otros pa\u00edses<\/strong>. Precis\u00f3 que el objetivo es asignar las dosis en los \u00faltimos tres meses de este a\u00f1o y durante el 2022.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cEsta nueva iniciativa con el fondo rotatorio pondr\u00e1 a disposici\u00f3n decenas de millones de dosis de vacunas de COVID-19 m\u00e1s all\u00e1 de 20% que ofrece Covax y complementar\u00e1 los acuerdos bilaterales. <strong>M\u00e1s de 20 pa\u00edses de la regi\u00f3n<\/strong> han expresado su inter\u00e9s en esta nueva oportunidad\u201d.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, el subdirector de la OPS, Jarbas Barbosa, se\u00f1al\u00f3 que han hablado con las autoridades venezolanas sobre la posibilidad de que<strong> el pa\u00eds cancele la deuda que tiene con el Fondo Rotatorio de la OPS para poder acceder a m\u00e1s vacunas contra el coronavirus<\/strong>. \u00ab<span style=\"font-weight: 400;\">Venezuela va a tener que buscar fondos adicionales para que se puedan cubrir todos los costos de tener acceso a esta nueva alternativa que complementar\u00e1 los esfuerzos que ya se est\u00e1n haciendo\u00bb, asegur\u00f3.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/07\/28\/ops-entre-julio-y-septiembre-llegaran-vacunas-sinopharm-y-sinovac-compradas-a-covax\/\">Leer m\u00e1s:\u00a0<\/a><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/07\/28\/ops-entre-julio-y-septiembre-llegaran-vacunas-sinopharm-y-sinovac-compradas-a-covax\/\">OPS: \u00abEntre julio y septiembre llegar\u00e1n vacunas Sinopharm y Sinovac compradas a Covax\u00bb<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que las primeras vacunas que llegar\u00e1n por Covax ser\u00e1n Sinovac.<\/p>\n","protected":false},"author":1,"featured_media":2882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[156,72,77,118,157,71],"class_list":["post-3094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-agosto","tag-covax","tag-covid-19","tag-dosis","tag-septiembre","tag-vacunas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPS: &quot;Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto&quot; - Salud Cr\u00edtica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPS: &quot;Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto&quot; - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que las primeras vacunas que llegar\u00e1n por Covax ser\u00e1n Sinovac.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T19:58:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"OPS: \u00abPrimer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\u00bb\",\"datePublished\":\"2021-08-11T19:58:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg\",\"keywords\":[\"agosto\",\"Covax\",\"COVID-19\",\"dosis\",\"septiembre\",\"vacunas\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\",\"name\":\"OPS: \\\"Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\\\" - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg\",\"datePublished\":\"2021-08-11T19:58:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg\",\"width\":840,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPS: \u00abPrimer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPS: \"Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\" - Salud Cr\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/","og_locale":"es_ES","og_type":"article","og_title":"OPS: \"Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\" - Salud Cr\u00edtica","og_description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que las primeras vacunas que llegar\u00e1n por Covax ser\u00e1n Sinovac.","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-08-11T19:58:33+00:00","og_image":[{"width":840,"height":560,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"OPS: \u00abPrimer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\u00bb","datePublished":"2021-08-11T19:58:33+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg","keywords":["agosto","Covax","COVID-19","dosis","septiembre","vacunas"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/","name":"OPS: \"Primer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\" - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg","datePublished":"2021-08-11T19:58:33+00:00","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/07\/Sinovax.jpg","width":840,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/11\/ops-primer-cargamento-de-vacunas-de-covax-podria-llegar-a-finales-de-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"OPS: \u00abPrimer cargamento de vacunas de Covax podr\u00eda llegar a finales de agosto\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3094"}],"version-history":[{"count":2,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3094\/revisions"}],"predecessor-version":[{"id":3097,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3094\/revisions\/3097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/2882"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}