{"id":3078,"date":"2021-08-10T17:06:18","date_gmt":"2021-08-10T21:06:18","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3078"},"modified":"2021-08-11T19:18:44","modified_gmt":"2021-08-11T23:18:44","slug":"gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/","title":{"rendered":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 10 de agosto de 2021.-\u00a0\u00a0<\/strong>\u00abFue horrible, horrible. <strong>Hab\u00eda gente del viernes, del s\u00e1bado, del lunes y de hoy (martes)<\/strong>. Atendieron como a 500 personas. El proceso fue muy lento y engorroso, sin distanciamiento\u00bb. Este es el testimonio de Jes\u00fas Quintero, un joven de 27 a\u00f1os, a quien le correspond\u00eda aplicarse la segunda dosis de <a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\">Sinopharm el 6 de agosto de 2021<\/a>. Debido a las primarias del Partido Socialista Unido de Venezuela, que se celebraron el 8 de agosto, el gobierno <strong>orden\u00f3 suspender las jornadas de vacunaci\u00f3n<\/strong> en algunos puntos para habilitarlos como centros de votaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Quintero logr\u00f3 vacunarse este 10 de agosto en la <strong>Escuela B\u00e1sica Rafael Antonio Godoy<\/strong>, en el estado M\u00e9rida. Le entregaron el 488, de aproximadamente 500 n\u00fameros que repartieron. Lleg\u00f3 a las 9:00am y sali\u00f3 casi a las 3:00pm. Record\u00f3 que cuando se puso la primera dosis no tard\u00f3 ni dos horas.<\/p>\n<p>&nbsp;<\/p>\n<p>El 6 de agosto, el joven se dirigi\u00f3 hasta el centro educativo para recibir la<a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/07\/20\/venezuela-no-ha-publicado-ni-un-contrato-de-los-cuatro-firmados-para-comprar-vacunas-anti-covid-19\/\"> segunda dosis de la vacuna china<\/a>, pero <strong>encontr\u00f3 las puertas cerradas y miembros del Plan Rep\u00fablica<\/strong> que informaban la suspensi\u00f3n de la jornada a partir de ese viernes y la reanudaci\u00f3n a partir de este martes.\u00a0 \u00abEl guardia me dijo que esa escuela iba a funcionar como centro preventivo para vacunar a las personas que prestar\u00edan apoyo en las elecciones internas del Psuv\u00bb, cont\u00f3 a Salud Cr\u00edtica.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3084\" style=\"width: 498px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-3084\" class=\"wp-image-3084\" src=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-10-at-4.00.55-PM-300x225.jpeg\" alt=\"\" width=\"488\" height=\"368\" \/><p id=\"caption-attachment-3084\" class=\"wp-caption-text\">Jes\u00fas Quintero asegur\u00f3 que la jornada de vacunaci\u00f3n que agrupaba a convocados de cuatro d\u00eda se registr\u00f3 con un ritmo muy lento | Foto: Jes\u00fas Quintero<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>De acuerdo con registros de Transparencia Venezuela, en este centro aplican diariamente entre<strong> 200 y 600 dosis<\/strong>.\u00a0 En la Escuela B\u00e1sica Vicente D\u00e1vila, M\u00e9rida, tambi\u00e9n suspendieron la vacunaci\u00f3n para acondicionarla como centro de votaci\u00f3n. All\u00ed se aplican entre 60 y 80 dosis diariamente.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/05\/encuesta-de-transparencia-venezuela-revela-que-40-de-consultados-conoce-casos-sobre-pago-de-vacunas-anti-covid-19\/\">Leer m\u00e1s:\u00a0<\/a><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/05\/encuesta-de-transparencia-venezuela-revela-que-40-de-consultados-conoce-casos-sobre-pago-de-vacunas-anti-covid-19\/\">Encuesta de Transparencia Venezuela revela que 40% de consultados conoce casos sobre pago de vacunas anti-COVID-19<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En Caracas, cerraron el centro de vacunaci\u00f3n que se encuentra en la<strong> Universidad Bolivariana de Venezuela<\/strong>, uno de los puntos con m\u00e1s capacidad para vacunar en la capital: entre 600 y 1.000 personas diarias. El Programa de Educaci\u00f3n-Acci\u00f3n en Derechos Humanos (Provea) denunci\u00f3 el 5 de agosto que decenas de <strong>adultos mayores<\/strong> llegaron a las instalaciones de la universidad para ser vacunados, pero fueron reprogramados para este martes.<\/p>\n<p>&nbsp;<\/p>\n<p>Una situaci\u00f3n similar se registr\u00f3 en<strong> Ruiz Pineda, parroquia Caricuao<\/strong>. En la puerta del Liceo Francisco Fajardo, pegaron un aviso que dec\u00eda: \u00abLa jornada de vacunaci\u00f3n queda suspendida hasta el d\u00eda lunes 09\/08\/2021\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>A la falta de segundas dosis de Sputnik-V y al lento ritmo de vacunaci\u00f3n anti-COVID-19, se suma el atraso por tres d\u00edas de suspensi\u00f3n de la jornada. Mar\u00eda Fernanda Rodr\u00edguez, habitante de M\u00e9rida, public\u00f3 en su cuenta de Twitter que el 8 de agosto en la noche recibi\u00f3 el mensaje de texto para vacunarse al d\u00eda siguiente: <strong><a href=\"https:\/\/twitter.com\/rodriguezasecas\/status\/1424847595374010375\">\u00ab\u00bfAdivinen? Perd\u00ed el viaje y mi tiempo,<\/a><\/strong> porque fue gente citada desde el viernes, cuando cerraron el centro para usarlo en las elecciones de ayer\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Actualizaci\u00f3n: hoy volv\u00ed a perder el tiempo y la gasolina que no me sobra y sigo sin ser vacunada. Hab\u00eda una cola infinita y no alcanzaron las dosis para todos los citados. Esas son las secuelas de suspender centros de vacunaci\u00f3n para uso electoral. Irresponsables. \ud83d\ude21 <a href=\"https:\/\/t.co\/hp3iLKG7Vv\">https:\/\/t.co\/hp3iLKG7Vv<\/a><\/p>\n<p>&mdash; Mar\u00eda Fernanda Rodr\u00edguez est\u00e1 sin luz, siempre. (@rodriguezasecas) <a href=\"https:\/\/twitter.com\/rodriguezasecas\/status\/1425164756730646529?ref_src=twsrc%5Etfw\">August 10, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/6Ago?src=hash&amp;ref_src=twsrc%5Etfw\">#6Ago<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/M%C3%A9rida?src=hash&amp;ref_src=twsrc%5Etfw\">#M\u00e9rida<\/a> Suspendidas jornadas de vacunaci\u00f3n <a href=\"https:\/\/twitter.com\/hashtag\/Covid_19?src=hash&amp;ref_src=twsrc%5Etfw\">#Covid_19<\/a> hasta el pr\u00f3ximo martes por elecciones internas del Psuv, centro de vacunaci\u00f3n Escuela B\u00e1sica Rafael A.  Godoy d\u00f3nde Plan Rep\u00fablica tom\u00f3 instalaciones. 8:30am <a href=\"https:\/\/twitter.com\/ReporteYa?ref_src=twsrc%5Etfw\">@ReporteYa<\/a> <a href=\"https:\/\/t.co\/7hdgIkUd7m\">https:\/\/t.co\/7hdgIkUd7m<\/a> <a href=\"https:\/\/t.co\/3fs6eb4wUN\">pic.twitter.com\/3fs6eb4wUN<\/a><\/p>\n<p>&mdash; Jes\u00fas Quintero Quiroz (@jquinteronews) <a href=\"https:\/\/twitter.com\/jquinteronews\/status\/1423626387722838020?ref_src=twsrc%5Etfw\">August 6, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv<\/p>\n","protected":false},"author":1,"featured_media":3079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[129,154,77,117,155,83],"class_list":["post-3078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desinformacion-y-vacunacion","tag-caracas","tag-centros","tag-covid-19","tag-merida","tag-suspension","tag-vacunacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-10T21:06:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-11T23:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2080\" \/>\n\t<meta property=\"og:image:height\" content=\"1560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv\",\"datePublished\":\"2021-08-10T21:06:18+00:00\",\"dateModified\":\"2021-08-11T23:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\"},\"wordCount\":605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg\",\"keywords\":[\"Caracas\",\"centros\",\"COVID-19\",\"M\u00e9rida\",\"suspensi\u00f3n\",\"vacunaci\u00f3n\"],\"articleSection\":[\"Desinformaci\u00f3n y vacunaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\",\"name\":\"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg\",\"datePublished\":\"2021-08-10T21:06:18+00:00\",\"dateModified\":\"2021-08-11T23:18:44+00:00\",\"description\":\"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg\",\"width\":2080,\"height\":1560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica","description":"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica","og_description":"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-08-10T21:06:18+00:00","article_modified_time":"2021-08-11T23:18:44+00:00","og_image":[{"width":2080,"height":1560,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv","datePublished":"2021-08-10T21:06:18+00:00","dateModified":"2021-08-11T23:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/"},"wordCount":605,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg","keywords":["Caracas","centros","COVID-19","M\u00e9rida","suspensi\u00f3n","vacunaci\u00f3n"],"articleSection":["Desinformaci\u00f3n y vacunaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/","name":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg","datePublished":"2021-08-10T21:06:18+00:00","dateModified":"2021-08-11T23:18:44+00:00","description":"Seis horas esper\u00f3 un joven de 27 a\u00f1os para ser vacunado en una escuela de M\u00e9rida este 10 de agosto. Le correspond\u00eda la segunda dosis el 6 de agosto, pero el centro estaba cerrado por las primarias del Psuv","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/vacunacion-en-Merida.jpeg","width":2080,"height":1560},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/10\/gobierno-suspendio-jornada-de-vacunacion-y-habilito-centros-para-las-primarias-del-psuv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Gobierno suspendi\u00f3 jornada de vacunaci\u00f3n y habilit\u00f3 centros para las primarias del Psuv"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3078"}],"version-history":[{"count":6,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3078\/revisions"}],"predecessor-version":[{"id":3100,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3078\/revisions\/3100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/3079"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}