{"id":3039,"date":"2021-08-04T14:39:15","date_gmt":"2021-08-04T18:39:15","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=3039"},"modified":"2021-09-07T14:04:16","modified_gmt":"2021-09-07T18:04:16","slug":"covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/","title":{"rendered":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2,6 millones de vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 04 de agosto de 2021.-\u00a0<\/strong>Entre agosto y septiembre de este a\u00f1o, el mecanismo <a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/07\/14\/ops-sinovac-y-sinopharm-estan-entre-las-opciones-de-vacunas-anti-covid-para-venezuela\/\">Covax enviar\u00e1 a Venezuela<\/a> 3.288.000 vacunas contra el coronavirus. Esta asignaci\u00f3n corresponde a la primera ronda de entrega al pa\u00eds, de acuerdo con la Organizaci\u00f3n Panamericana de la Salud (OPS).<\/p>\n<p>&nbsp;<\/p>\n<p>En rueda de prensa de este 4 de agosto, el director de Emergencias en Salud de la OPS, Ciro Ugarte, precis\u00f3 que <strong>2,6 millones de dosis ser\u00e1n Sinopharm y 600.000 Sinovac. <\/strong>En la siguiente ronda de entrega, de la que no se tiene fecha a\u00fan, Covax completar\u00e1 las dosis para cubrir a 20% de la poblaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>El total de vacunas que indica la OPS no coincide con la cantidad que declar\u00f3 Maduro recientemente. \u00ab<span style=\"font-weight: 400;\">Ya Covax ha confirmado que va entregar a Venezuela vacunas para <strong>6.200.000 personas<\/strong>\u00ab, dijo el pasado 1\u00b0 de agosto en una transmisi\u00f3n de radio y televisi\u00f3n junto a la vicepresidenta de la Rep\u00fablica, Delcy Rodr\u00edguez, y el ministro de Salud, Carlos Alvarado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>En el tablero de mercado vacuna contra la COVID-19 de <a href=\"https:\/\/www.unicef.org\/supply\/covid-19-vaccine-market-dashboard\">Unicef se ve reflejada la asignaci\u00f3n para el pa\u00eds<\/a>. Venezuela y Guyana Francesa son los \u00fanicos de Suram\u00e9rica que no han recibido una dosis de vacuna a trav\u00e9s del Covax.<\/p>\n<p>&nbsp;<\/p>\n<p>De forma p\u00fablica y bajo la figura de donaci\u00f3n por parte de China, <strong>Venezuela recibi\u00f3 publicamente hasta junio al menos 1,8 millones de dosis Sinopharm<\/strong>, con las que se comenz\u00f3 a vacunar a las personas menores de 60 a\u00f1os de edad.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/03\/maduro-asegura-que-covax-enviara-vacunas-para-62-millones-de-venezolanos\/\">Leer m\u00e1s:\u00a0<\/a><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/03\/maduro-asegura-que-covax-enviara-vacunas-para-62-millones-de-venezolanos\/\">Maduro asegura que Covax enviar\u00e1 vacunas para 6,2 millones de venezolanos<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Las autoridades de Venezuela se han propuesto vacunar a 70% de la poblaci\u00f3n al cierre de 2021. Esto significar\u00eda inmunizar a al menos 22 millones de personas y para cumplir con la meta se necesitar\u00edan 44 millones de dosis. Sin embargo, de forma p\u00fablica al pa\u00eds han llegado 3.230.000 vacunas.<\/p>\n<p>&nbsp;<\/p>\n<p>De acuerdo con Our World In Data, hasta el 12 de julio Venezuela administraba 14.07 dosis por cada 100 habitantes, y seg\u00fan el Ministerio de Salud, 4.677.000 venezolanos han recibido al menos una dosis de vacuna contra la COVID-19, es decir 16,2% de la poblaci\u00f3n. Sin embargo, se desconoce cu\u00e1ntas personas han completado su esquema de vacunaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>En cambio, pa\u00edses como Chile y Canada que registran 134,18 y 131,33 dosis por cada 100 habitantes, respectivamente, reportan m\u00e1s del 60% de la poblaci\u00f3n parcialmente vacunada. Ambos pa\u00edses podr\u00edan alcanzar la inmunidad de reba\u00f1o este a\u00f1o, seg\u00fan el seguimiento que hace la <strong>Unidad de Pol\u00edticas P\u00fablicas de la Universidad Sim\u00f3n Bol\u00edvar<\/strong> a la vacunaci\u00f3n en Am\u00e9rica Latina.<\/p>\n<p>&nbsp;<\/p>\n<a href=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/08\/USB-UPP.-No.-19.-Seguimiento-de-vacunaciones-COVID-19-en-AL.pdf\" class=\"pdfemb-viewer\" style=\"width:600px;height:600px;\" data-width=\"600\" data-height=\"600\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">USB-UPP. No. 19. Seguimiento de vacunaciones COVID-19 en AL<\/a>\n","protected":false},"excerpt":{"rendered":"<p>El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n de Sinopharm y 600.000 de Sinovac\u00a0<\/p>\n","protected":false},"author":1,"featured_media":2620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[72,77,74,83,73],"class_list":["post-3039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-covax","tag-covid-19","tag-ops","tag-vacunacion","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T18:39:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-07T18:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega\",\"datePublished\":\"2021-08-04T18:39:15+00:00\",\"dateModified\":\"2021-09-07T18:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\"},\"wordCount\":506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png\",\"keywords\":[\"Covax\",\"COVID-19\",\"OPS\",\"vacunaci\u00f3n\",\"Venezuela\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\",\"name\":\"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png\",\"datePublished\":\"2021-08-04T18:39:15+00:00\",\"dateModified\":\"2021-09-07T18:04:16+00:00\",\"description\":\"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica","description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/","og_locale":"es_ES","og_type":"article","og_title":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica","og_description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-08-04T18:39:15+00:00","article_modified_time":"2021-09-07T18:04:16+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png","type":"image\/png"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega","datePublished":"2021-08-04T18:39:15+00:00","dateModified":"2021-09-07T18:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/"},"wordCount":506,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png","keywords":["Covax","COVID-19","OPS","vacunaci\u00f3n","Venezuela"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/","name":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png","datePublished":"2021-08-04T18:39:15+00:00","dateModified":"2021-09-07T18:04:16+00:00","description":"El director de Emergencias en Salud de la OPS, Ciro Ugarte, inform\u00f3 que de la cantidad total, 2.600.000 vacunas ser\u00e1n Sinopharm y 600.000 Sinovac\u00a0","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/denuncia-2.png","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/08\/04\/covax-asigna-a-venezuela-3-288-000-vacunas-anti-covid-19-en-primera-ronda-de-entrega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Covax asigna a Venezuela 3.288.000 vacunas anti-COVID-19 en primera ronda de entrega"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=3039"}],"version-history":[{"count":6,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3039\/revisions"}],"predecessor-version":[{"id":3371,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/3039\/revisions\/3371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/2620"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=3039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=3039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=3039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}