{"id":2665,"date":"2021-06-28T18:40:50","date_gmt":"2021-06-28T22:40:50","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=2665"},"modified":"2021-06-29T08:03:37","modified_gmt":"2021-06-29T12:03:37","slug":"hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/","title":{"rendered":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 26 de junio de 2021.-\u00a0<\/strong>Una banda delictiva que se dedicaba a comercializar\u00a0 supuestas vacunas contra el coronavirus fue desmantelada el 23 de junio por la Polic\u00eda del estado Lara. De acuerdo con una publicaci\u00f3n de <a href=\"https:\/\/epthelinkdos.tk\/alianzas\/casi-2-000-larenses-pagaron-entre-100-y-450-dolares-por-falsas-vacunas-anti-covid-19\/\">El Pitazo<\/a>, casi 2.000 personas pagaron entre <strong>USD 100 y USD 400 por dosis<\/strong> que conten\u00edan agua hervida, antibi\u00f3ticos y analg\u00e9sicos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abLas v\u00edctimas <strong>recib\u00edan un comprobante que no est\u00e1 avalado por el Ministerio de Salud<\/strong> ni se asemeja al entregado en la jornada de vacunaci\u00f3n masiva vigente. Una fuente policial declar\u00f3, en condici\u00f3n de anonimato, que los implicados en la estafa aplicaban las vacunas a domicilio y ofrec\u00edan el servicio a empresas y negocios\u00bb, rese\u00f1a el medio de comunicaci\u00f3n digital.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan el director de Salud de la entidad, Javier Cabrera, la banda delictiva convocaba a grupos de personas para aplicarles las supuestas dosis, pero en realidad recib\u00edan ampicilina.<\/p>\n<p>&nbsp;<\/p>\n<p>Los miembros de esta red fueron identificados como Yoandri Jos\u00e9 Garc\u00eda, de 35 a\u00f1os; Jes\u00fas Antonio Cabrales Mel\u00e9ndez, de 21 a\u00f1os; Mar\u00eda Estrella P\u00e9rez de Troconis, de 52 a\u00f1os, y Andre\u00edna Jos\u00e9 Mel\u00e9ndez, de 34 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la detenci\u00f3n, las autoridades decomisaron comprobantes de vacunaci\u00f3n falsos, USD 1.400 en efectivo, seis tel\u00e9fonos, <strong>125 jeringas<\/strong> que conten\u00edan la sustancia, 43 jeringas vac\u00edas, una cava y dos carros.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/16\/alcalde-de-tachira-privilegia-a-las-ubch-en-la-vacunacion-anti-covid-19\/\">Leer m\u00e1s:\u00a0<\/a><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/16\/alcalde-de-tachira-privilegia-a-las-ubch-en-la-vacunacion-anti-covid-19\/\">Alcalde de T\u00e1chira privilegia a las UBCH en la vacunaci\u00f3n anti-COVID-19<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Cabrera exhort\u00f3 a las personas que fueron estafadas a dirigirse hasta la Polic\u00eda del estado Lara para colaborar con las investigaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>Hace semanas, <strong>Transparencia Venezuela<\/strong> inici\u00f3 una <a href=\"https:\/\/transparenciave.org\/transparencia-venezuela-crea-conciencia-ante-comercio-ilicito-de-vacunas\/\">campa\u00f1a de concientizaci\u00f3n<\/a> para alertar sobre los riesgos de corrupci\u00f3n del mercado negro.\u00a0 No solo hay consecuencias legales cuando se compra una vacuna, sino que est\u00e1 en juego la vida de quienes deciden involucrarse en el mercado negro, porque no hay garant\u00edas de que la dosis que reciban se corresponda con la vacuna, o de que haya sido almacenada de manera adecuada.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n est\u00e1 en riesgo la vida de los grupos prioritarios, como trabajadores sanitarios y adultos mayores, que a\u00fan no han sido inmunizados, al perder la oportunidad de recibir la dosis que les corresponde.\u00a0Las vacunas contra la COVID-19 son un bien del Estado, y su resguardo es responsabilidad del gobierno.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas<\/p>\n","protected":false},"author":1,"featured_media":2666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[55,77,113,112],"class_list":["post-2665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corrupcion-con-vacunas","tag-corrupcion","tag-covid-19","tag-lara","tag-vacunas-falsas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T22:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-29T12:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas\",\"datePublished\":\"2021-06-28T22:40:50+00:00\",\"dateModified\":\"2021-06-29T12:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg\",\"keywords\":[\"corrupci\u00f3n\",\"COVID-19\",\"Lara\",\"vacunas falsas\"],\"articleSection\":[\"Corrupci\u00f3n con vacunas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\",\"name\":\"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg\",\"datePublished\":\"2021-06-28T22:40:50+00:00\",\"dateModified\":\"2021-06-29T12:03:37+00:00\",\"description\":\"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg\",\"width\":1170,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica","description":"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/","og_locale":"es_ES","og_type":"article","og_title":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica","og_description":"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-06-28T22:40:50+00:00","article_modified_time":"2021-06-29T12:03:37+00:00","og_image":[{"width":1170,"height":530,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas","datePublished":"2021-06-28T22:40:50+00:00","dateModified":"2021-06-29T12:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg","keywords":["corrupci\u00f3n","COVID-19","Lara","vacunas falsas"],"articleSection":["Corrupci\u00f3n con vacunas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/","name":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg","datePublished":"2021-06-28T22:40:50+00:00","dateModified":"2021-06-29T12:03:37+00:00","description":"Una banda delictiva que operaba en el estado Lara vend\u00eda supuestas vacunas y entregaba comprobantes falsos. Las autoridades decomisaron dinero en efectivo y m\u00e1s de 100 jeringas","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/vacunas-falsas.jpg","width":1170,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/28\/hasta-usd-400-pagaron-en-lara-por-vacunas-anti-covid-19-falsas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Hasta USD 400 pagaron en Lara por vacunas anti-COVID-19 falsas"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=2665"}],"version-history":[{"count":3,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2665\/revisions"}],"predecessor-version":[{"id":2674,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2665\/revisions\/2674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/2666"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=2665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=2665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=2665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}