{"id":2388,"date":"2021-06-09T18:09:32","date_gmt":"2021-06-09T22:09:32","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=2388"},"modified":"2021-06-09T18:46:51","modified_gmt":"2021-06-09T22:46:51","slug":"ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/","title":{"rendered":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Por segunda vez consecutiva, la organizaci\u00f3n desmiente a Nicol\u00e1s Maduro, quien ha dicho que el pago de las vacunas ya se concret\u00f3 y en julio deber\u00edan llegar al menos cinco millones de dosis<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 9 de junio de 2021.-\u00a0<\/strong>Venezuela sigue sin acceder a las vacunas anti-COVID-19 que provee el mecanismo Covax. La Organizaci\u00f3n Panamericana de la Salud (OPS) asegur\u00f3 este 9 de junio que la deuda del Estado venezolano a la Alianza Gavi es de 10 millones de d\u00f3lares, la misma cifra que se reporta desde la \u00faltima semana de mayo.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante una conferencia de prensa, el director de Emergencias de la OPS, Ciro Ugarte, insisti\u00f3 en que no han recibido la confirmaci\u00f3n del \u00faltimo pago para completar los 120 millones de d\u00f3lares que permiten acceder a m\u00e1s de 11,3 millones de vacunas anti-COVID-19.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abQuisiera resaltar otra vez la apertura de todas las partes internas e internacionales para procurar la mayor cantidad de vacunas a Venezuela y lo m\u00e1s pronto posible (&#8230;) Hay una preocupaci\u00f3n de que es necesario avanzar con mayor propiedad y que podamos tener informaci\u00f3n sobre el avance de procesos internos, del pago que se tiene que realizar y del tipo de vacunas que estar\u00e1 disponible\u00bb, expres\u00f3 Ugarte.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/ops-asegura-que-venezuela-vacuno-a-364-000-personas-hasta-abril\/\">Leer m\u00e1s: OPS: En Venezuela se han vacunado 364.000 personas hasta abril\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Semanas atr\u00e1s Ugarte hab\u00eda se\u00f1alado la probabilidad de que Venezuela entrara en la lista de distribuci\u00f3n para el mes de julio. Este mi\u00e9rcoles dijo: \u00abNo creo que esas vacunas est\u00e9n disponibles muy pronto\u00bb. No obstante, aclar\u00f3 que Venezuela es una prioridad en la regi\u00f3n, debido a que no ha recibido ni una dosis a trav\u00e9s del mecanismo Covax.<\/p>\n<p>&nbsp;<\/p>\n<p>Por segunda vez consecutiva, la OPS desmiente a Nicol\u00e1s Maduro, quien ha se\u00f1alado en dos oportunidades-30 de mayo y 6 de junio- que el pago a Covax ya se concret\u00f3 y al menos cinco millones de dosis de vacunas deber\u00edan llegar en julio. \u00abEl sistema Covax tiene una deuda con Venezuela. Le hicimos un dep\u00f3sito en abril y estamos a la espera de las vacunas\u00bb, afirm\u00f3 el domingo, 6 de junio.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/19\/ops-informa-que-venezuela-mantiene-una-deuda-de-18-millones-de-dolares-con-covax\/\">Leer m\u00e1s: OPS informa que Venezuela mantiene una deuda de 18 millones de d\u00f3lares con Covax\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En horas de la tarde de este mi\u00e9rcoles, la presidenta de la Comisi\u00f3n Presidencial para la Prevenci\u00f3n y el Control de la COVID-19, Delcy Rodr\u00edguez, el canciller Jorge Arreaza, y el ministro de Salud, Carlos Alvarado, se reunieron con el representante de la OPS en el pa\u00eds, Gerardo de Cos\u00edo, para \u00abreclamar el retraso del mecanismo Covax\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3<\/p>\n","protected":false},"author":1,"featured_media":2390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[72,74,71,73],"class_list":["post-2388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-covax","tag-ops","tag-vacunas","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T22:09:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T22:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax\",\"datePublished\":\"2021-06-09T22:09:32+00:00\",\"dateModified\":\"2021-06-09T22:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg\",\"keywords\":[\"Covax\",\"OPS\",\"vacunas\",\"Venezuela\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\",\"name\":\"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg\",\"datePublished\":\"2021-06-09T22:09:32+00:00\",\"dateModified\":\"2021-06-09T22:46:51+00:00\",\"description\":\"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica","description":"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/","og_locale":"es_ES","og_type":"article","og_title":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica","og_description":"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-06-09T22:09:32+00:00","article_modified_time":"2021-06-09T22:46:51+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax","datePublished":"2021-06-09T22:09:32+00:00","dateModified":"2021-06-09T22:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg","keywords":["Covax","OPS","vacunas","Venezuela"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/","name":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg","datePublished":"2021-06-09T22:09:32+00:00","dateModified":"2021-06-09T22:46:51+00:00","description":"Por segunda vez consecutiva, la OPS desmiente a Maduro, quien ha dicho que el pago a Covax por las vacunas anti-COVID-19 ya se concret\u00f3","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/Covax.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/09\/ops-asegura-que-venezuela-aun-debe-10-millones-de-dolares-a-covax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"OPS asegura que Venezuela a\u00fan debe 10 millones de d\u00f3lares a Covax"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=2388"}],"version-history":[{"count":7,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2388\/revisions"}],"predecessor-version":[{"id":2397,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2388\/revisions\/2397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/2390"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=2388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=2388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=2388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}