{"id":2143,"date":"2021-06-03T13:00:52","date_gmt":"2021-06-03T17:00:52","guid":{"rendered":"https:\/\/transparenciave.org\/saludcritica\/?p=2143"},"modified":"2021-06-03T13:00:52","modified_gmt":"2021-06-03T17:00:52","slug":"gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas","status":"publish","type":"post","link":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/","title":{"rendered":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Hector Rodr\u00edguez, gobernador de Miranda, asegur\u00f3 que en el estado dispusieron 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo. Sin embargo, no detall\u00f3 c\u00f3mo se distribuir\u00edan<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Transparencia Venezuela, 1 de junio de 2021.-<\/strong> <span style=\"font-weight: 400;\">El gobernador del estado Miranda, H\u00e9ctor Rodr\u00edguez, anunci\u00f3 que durante la segunda fase de vacunaci\u00f3n contra la COVID-19, iniciada el pasado 29 de mayo, esperan inmunizar a 1.800.000 personas.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Luego de reunirse con los 21 alcaldes de la entidad el 31 de mayo, Rodr\u00edguez asegur\u00f3 que estaban \u201cactivando y dotando\u201d 29 puestos de vacunaci\u00f3n masiva, sin precisar las ubicaciones.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n se\u00f1al\u00f3 que en cada centro esperan aplicar 300 dosis diariamente, es decir, que ser\u00eda hasta el 31 de diciembre de 2021 cuando se llegue a inmunizar a aproximadamente 1.861.800 habitantes de la entidad. Esta cifra representa el 55,5% de la poblaci\u00f3n mirandina que es de 3.352.504, de acuerdo con el Instituto Nacional de Estad\u00edsticas (INE).\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No obstante, el alcalde de Chacao, Gustavo Duque, public\u00f3 en su cuenta de Twitter que durante la reuni\u00f3n se les inform\u00f3 que el objetivo es vacunar a 70% de la poblaci\u00f3n de Miranda. Es decir, que en ese municipio, donde solo se ha habilitado al Liceo Gustavo Herrera, deber\u00e1n inmunizar a un aproximado de 56.000 ciudadanos (70% de la poblaci\u00f3n de Chacao).\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tanto Duque, como los alcaldes de El Hatillo y Baruta, Elias Sayegh y Darwin Gonz\u00e1lez, respectivamente, advirtieron que el proceso de vacunaci\u00f3n es coordinado por el Ministerio de Salud y la convocatoria se realiza a trav\u00e9s del sistema patria.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, indicaron que la vacuna Sinopharm ser\u00e1 aplicada a los adultos con edades comprendidas entre 18 y 59 a\u00f1os, mientras que los mayores de 60 a\u00f1os recibir\u00e1n la Sputnik-V.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/05\/25\/venezuela-encabeza-el-indice-de-letalidad-por-covid-19-en-trabajadores-de-la-salud\/\">Leer m\u00e1s: Venezuela encabeza el \u00edndice de letalidad por COVID-19 en trabajadores de la salud\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Cantidad de dosis desconocidas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Hasta ahora, ni los alcaldes ni el gobernador han informado sobre la cantidad de dosis que han llegado a cada punto de vacunaci\u00f3n masiva. Sayegh asom\u00f3 a trav\u00e9s de un comunicado que por el momento solo contaban con 4% de las vacunas que se requer\u00edan en la entidad.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La alcaldesa del municipio Urdaneta, Gabriela Simoza, escribi\u00f3 en su cuenta de Twitter el 1 de junio que un lote de vacunas Sputnik-V estaba saliendo a los Valles del Tuy \u201cpara iniciar pronto el proceso masivo de vacunaci\u00f3n\u201d, pero no detall\u00f3 la cantidad de dosis ni los puestos de vacunaci\u00f3n. Tampoco lo hizo Nora Delgado, alcaldesa del municipio Bri\u00f3n, quien anunci\u00f3 que las vacunas llegaban a Barlovento, Guarenas y Guatire.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Los puntos en Guarenas ser\u00e1n las escuelas Ambrosio Plaza y Creaci\u00f3n Trapichito, seg\u00fan una publicaci\u00f3n del alcalde Luis Figueroa en su cuenta de Twitter. Mientras que en El Hatillo se habilit\u00f3 en la <\/span><span style=\"font-weight: 400;\">Unidad Educativa Juana Aponte en El Calvario.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cDesde la alcald\u00eda hemos propuesto otros puntos de vacunaci\u00f3n y nos hemos puesto a la orden para colaborar con el plan de vacunaci\u00f3n. Nuestra prioridad es la salud de nuestros vecinos. Se nos dijo que a medida que lleguen m\u00e1s vacunas se podr\u00e1n abrir otros centros de vacunaci\u00f3n en nuestro municipio\u201d, manifest\u00f3 Sayegh en un comunicado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">En cambio, otras autoridades locales como Salvador Medina (Sim\u00f3n Bol\u00edvar) y Jos\u00e9 Vicente Rangel \u00c1valos (Sucre) ni siquiera han informado sobre esta reuni\u00f3n con la gobernaci\u00f3n ni los puntos dispuestos para la vacunaci\u00f3n en cada municipio.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>El pasado 28 de mayo, el ministro de Salud, Carlos Alvarado, inform\u00f3 que la segunda fase de vacunaci\u00f3n iniciar\u00eda al d\u00eda siguiente en 27 puntos a nivel nacional, hasta llegar a 77, sin detallar la distribuci\u00f3n por estados y municipios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo<\/p>\n","protected":false},"author":1,"featured_media":2144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[84,81,82,85,83],"class_list":["post-2143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-saber","tag-alcaldias","tag-gobernacion","tag-miranda","tag-salud","tag-vacunacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica<\/title>\n<meta name=\"description\" content=\"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica\" \/>\n<meta property=\"og:description\" content=\"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud Cr\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T17:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"847\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vanzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vanzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\"},\"author\":{\"name\":\"vanzola\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\"},\"headline\":\"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas\",\"datePublished\":\"2021-06-03T17:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg\",\"keywords\":[\"alcald\u00edas\",\"Gobernaci\u00f3n\",\"Miranda\",\"salud\",\"vacunaci\u00f3n\"],\"articleSection\":[\"Derecho a saber\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\",\"name\":\"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica\",\"isPartOf\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg\",\"datePublished\":\"2021-06-03T17:00:52+00:00\",\"description\":\"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo\",\"breadcrumb\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg\",\"width\":847,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/transparenciave.org\/saludcritica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#website\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"name\":\"Salud Cr\u00edtica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#organization\",\"name\":\"Salud Cr\u00edtica\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"contentUrl\":\"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png\",\"width\":280,\"height\":65,\"caption\":\"Salud Cr\u00edtica\"},\"image\":{\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8\",\"name\":\"vanzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g\",\"caption\":\"vanzola\"},\"sameAs\":[\"https:\/\/transparenciave.org\/saludcritica\"],\"url\":\"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica","description":"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/","og_locale":"es_ES","og_type":"article","og_title":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica","og_description":"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo","og_url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/","og_site_name":"Salud Cr\u00edtica","article_published_time":"2021-06-03T17:00:52+00:00","og_image":[{"width":847,"height":477,"url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg","type":"image\/jpeg"}],"author":"vanzola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vanzola","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#article","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/"},"author":{"name":"vanzola","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8"},"headline":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas","datePublished":"2021-06-03T17:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg","keywords":["alcald\u00edas","Gobernaci\u00f3n","Miranda","salud","vacunaci\u00f3n"],"articleSection":["Derecho a saber"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/","url":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/","name":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas - Salud Cr\u00edtica","isPartOf":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg","datePublished":"2021-06-03T17:00:52+00:00","description":"El gobernador de Miranda, Hector Rodr\u00edguez, inform\u00f3 la habilitaci\u00f3n de 29 puntos para la vacunaci\u00f3n masiva que inici\u00f3 el pasado 29 de mayo","breadcrumb":{"@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#primaryimage","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/06\/hector-rodriguez-coronavirus.jpg","width":847,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/transparenciave.org\/saludcritica\/2021\/06\/03\/gobernacion-de-miranda-promete-vacunar-a-18-millones-de-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transparenciave.org\/saludcritica\/"},{"@type":"ListItem","position":2,"name":"Gobernaci\u00f3n de Miranda promete vacunar a 1,8 millones de personas"}]},{"@type":"WebSite","@id":"https:\/\/transparenciave.org\/saludcritica\/#website","url":"https:\/\/transparenciave.org\/saludcritica\/","name":"Salud Cr\u00edtica","description":"","publisher":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transparenciave.org\/saludcritica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transparenciave.org\/saludcritica\/#organization","name":"Salud Cr\u00edtica","url":"https:\/\/transparenciave.org\/saludcritica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/","url":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/transparenciave.org\/saludcritica\/wp-content\/uploads\/2021\/05\/logo.png","width":280,"height":65,"caption":"Salud Cr\u00edtica"},"image":{"@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/3b30d2c6e81695912f2cb00844883cd8","name":"vanzola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transparenciave.org\/saludcritica\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ec45ada5df379dd964fc02061b9922b1d4399aca084c4bebc052b2571426260?s=96&d=mm&r=g","caption":"vanzola"},"sameAs":["https:\/\/transparenciave.org\/saludcritica"],"url":"https:\/\/transparenciave.org\/saludcritica\/author\/vanzola\/"}]}},"_links":{"self":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":4,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"predecessor-version":[{"id":2156,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/posts\/2143\/revisions\/2156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media\/2144"}],"wp:attachment":[{"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transparenciave.org\/saludcritica\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}